{"id":11130,"date":"2026-05-13T01:10:38","date_gmt":"2026-05-12T23:10:38","guid":{"rendered":"https:\/\/fiaf.net\/lazio\/?p=11130"},"modified":"2026-05-13T01:12:06","modified_gmt":"2026-05-12T23:12:06","slug":"primaverarte2026","status":"publish","type":"post","link":"https:\/\/fiaf.net\/lazio\/primaverarte2026\/","title":{"rendered":"PrimaverArte2026"},"content":{"rendered":"\n\t\t<div class=\"box success  \">\n\t\t\t<div class=\"box-inner-block\">\n\t\t\t\t<span class=\"fa tie-shortcode-boxicon\"><\/span>Il Movimento Artistico \u201cSpazioTempismo\u201d torna a Soriano nel Cimino con 23 Artisti in Mostra <em>PrimaverArte2026<\/em><\/p>\n<p>La Mostra sar\u00e0 aperta al pubblico dal 16 maggio\u00a0 fino al 7 giugno 2026<br \/>\ningresso <em>da venerd\u00ec a domenica <\/em><br \/>\n<em>orari:<\/em> <em>dalle 10:00 alle 13:00 e dalle 15:00 alle 19:00<\/em><em>.<\/em><\/p>\n<p>Come ormai consuetudine annuale, torna l\u2019evento del <em>Movimento SpazioTempismo \u201cPrimaverArte\u201d<\/em> a Soriano nel Cimino (VT) il 16 maggio alle ore 17,00 &#8211; <em>ingresso libero<\/em> &#8211; con l\u2019esposizione di 23 opere inedite di Fotografi e Artisti di tutte le discipline, presso lo storico Palazzo Chigi-Albani.<\/p>\n<p>Il \u201c<em>GESTO<\/em>\u201d dell\u2019Artista diventa \u201c<em>IPERGESTO<\/em>\u201d quando osserva il soggetto da pi\u00f9 prospettive rappresentandole nella continuit\u00e0 del Tempo<br \/>\nLa fotografia protagonista accanto a tutte le altre discipline artistiche<em>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/em><\/p>\n<p>Gli Artisti con la propria visione, con il proprio strumento, con il proprio stilema, con le proprie emozioni, si sono espressi nel rappresentare la multi-prospettiva nel fluire del tempo con l\u2019evidenza delle dematerializzazioni e ri-materializzazioni. Il concetto di <strong><em>SpazioTempismo<\/em><\/strong> \u00e8 stato rappresentato per mezzo della pittura, scultura, installazione, disegno, digital-art e fotografia (<strong><em>FoTotempismo<\/em><\/strong>) con la dimostrazione, quest\u2019ultima, di un vivo interesse da parte di abili fotografi ad esprimersi con questa nuova forma, creando cos\u00ec una connessione espressiva con lo sguardo fotografico e le altre diverse forme di espressione artistica. Il <strong><em>FoTotempismo<\/em><\/strong> non si accontenta di &#8220;congelare&#8221; un momento, ma mira a sintetizzare la quarta dimensione all&#8217;interno della bidimensionalit\u00e0.<\/p>\n<p>Il promotore e ideatore <em>Enzo Trifolelli<\/em> condurr\u00e0 l\u2019evento, coadiuvato da <em>Luciana Barbi<\/em>, entrambi fotografi iscritti <em>FIAF<\/em>. Interverranno il Gallerista <em>Silvio <\/em><em>Merlani<\/em> e gli Artisti delle varie discipline.<\/p>\n<p>Le opere esposte, tra le quali alcune fotografie, sono tutte rigorosamente di dimensioni cm 100&#215;100, come richiesto dal Bando e conformi al Manifesto e alla relativa <em>Dichiarazione Programmatica<\/em> dello <strong><em>SpazioTempismo<\/em><\/strong>.<\/p>\n<p>Le opere esposte riflettono la volont\u00e0 specifica di non fermarsi alla superficie dell\u2019immagine, ma di esaltare la ricerca estetica e contenutistica pi\u00f9 avanzata con l\u2019obiettivo di valorizzare il talento emergente e\/o consolidato, ponendo l&#8217;accento su una rigorosa ricerca di contenuti e su un&#8217;estetica contemporanea capace di dialogare con il presente. In un panorama visivo spesso saturo, la Mostra <strong>PrimaverArte2026<\/strong> si propone come una vetrina, offrendo agli artisti e al pubblico un contesto curato e dinamico, dove la qualit\u00e0 formale e l&#8217;innovazione concettuale si fondono per ridefinire i canoni dell\u2019immagine odierna.<\/p>\n<p>Queste opere vanno ad arricchire l\u2019ampia Collezione d\u2019Arte degli <em>Higlighted<\/em> in <strong><em>SpazioTempismo<\/em><\/strong> che al momento ne conta pi\u00f9 di 170 di 60 Artisti.<\/p>\n<p>informazioni: Segreteria: +39 349.7304356<\/p>\n<p>mail: <a href=\"mailto:info@spaziotempismo.it\">info@spaziotempismo.it<\/a><\/p>\n<p><a href=\"http:\/\/www.spaziotempismo.it\" target=\"_blank\" rel=\"noopener\">www.spaziotempismo.it<\/a><\/p>\n<p>Clicca sull&#8217;anteprima per la locandina:<\/p>\n<p><a href=\"https:\/\/fiaf.net\/lazio\/wp-content\/uploads\/sites\/13\/2026\/05\/Locandina.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-11137\" src=\"https:\/\/fiaf.net\/lazio\/wp-content\/uploads\/sites\/13\/2026\/05\/Locandina-212x300.jpeg\" alt=\"\" width=\"212\" height=\"300\" srcset=\"https:\/\/fiaf.net\/lazio\/wp-content\/uploads\/sites\/13\/2026\/05\/Locandina-212x300.jpeg 212w, https:\/\/fiaf.net\/lazio\/wp-content\/uploads\/sites\/13\/2026\/05\/Locandina-724x1024.jpeg 724w, https:\/\/fiaf.net\/lazio\/wp-content\/uploads\/sites\/13\/2026\/05\/Locandina-768x1086.jpeg 768w, https:\/\/fiaf.net\/lazio\/wp-content\/uploads\/sites\/13\/2026\/05\/Locandina-1086x1536.jpeg 1086w, https:\/\/fiaf.net\/lazio\/wp-content\/uploads\/sites\/13\/2026\/05\/Locandina.jpeg 1131w\" sizes=\"auto, (max-width: 212px) 100vw, 212px\" \/><\/a><\/p>\n\n    <div class=\"xs_social_share_widget xs_share_url after_content \t\tmain_content  wslu-style-1 wslu-share-box-shaped wslu-fill-colored wslu-none wslu-share-horizontal wslu-theme-font-no wslu-main_content\">\n\n\t\t\n        <ul>\n\t\t\t        <\/ul>\n    <\/div> \n","protected":false},"excerpt":{"rendered":"<p>Il Movimento Artistico \u201cSpazioTempismo\u201d torna a Soriano nel Cimino con 23 Artisti in Mostra PrimaverArte2026 La Mostra sar\u00e0 aperta al &hellip;<\/p>\n","protected":false},"author":20,"featured_media":11132,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8],"tags":[],"class_list":["post-11130","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mostre"],"acf":[],"_links":{"self":[{"href":"https:\/\/fiaf.net\/lazio\/wp-json\/wp\/v2\/posts\/11130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fiaf.net\/lazio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fiaf.net\/lazio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fiaf.net\/lazio\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/fiaf.net\/lazio\/wp-json\/wp\/v2\/comments?post=11130"}],"version-history":[{"count":9,"href":"https:\/\/fiaf.net\/lazio\/wp-json\/wp\/v2\/posts\/11130\/revisions"}],"predecessor-version":[{"id":11140,"href":"https:\/\/fiaf.net\/lazio\/wp-json\/wp\/v2\/posts\/11130\/revisions\/11140"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fiaf.net\/lazio\/wp-json\/wp\/v2\/media\/11132"}],"wp:attachment":[{"href":"https:\/\/fiaf.net\/lazio\/wp-json\/wp\/v2\/media?parent=11130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fiaf.net\/lazio\/wp-json\/wp\/v2\/categories?post=11130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fiaf.net\/lazio\/wp-json\/wp\/v2\/tags?post=11130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}