{"id":1718,"date":"2020-06-15T12:58:53","date_gmt":"2020-06-15T12:58:53","guid":{"rendered":"https:\/\/fiaf.net\/portfolioitalia\/?p=1718"},"modified":"2020-06-15T12:58:53","modified_gmt":"2020-06-15T12:58:53","slug":"seconda-tappa-2020-online","status":"publish","type":"post","link":"https:\/\/fiaf.net\/portfolioitalia\/seconda-tappa-2020-online\/","title":{"rendered":"Seconda Tappa 2020 online"},"content":{"rendered":"<p>Risultati del\u00a0<strong>\u00ab17\u00b0 FotoArte in Portfolio\u00bb<\/strong>\u00a0seconda delle dieci Selezioni aderenti a\u00a0<strong>\u00abPortfolio Italia 2020\u00a0\u2013 Gran Premio Fujifilm\u00bb<\/strong><br \/>\n<!--more--><br \/>\nIl <strong>\u00ab<\/strong><strong>17\u00b0 FotoArte in Portfolio\u00bb<\/strong> (organizzato dal Circolo Fotografico Il Castello di Taranto) si \u00e8 tenuto, in versione online (per la seconda volta in questa 17<sup>a<\/sup> edizione di \u201cPortfolio Italia\u201d), nelle giornate di sabato 13 e domenica 14 giugno 2020. Agli Incontri hanno partecipato 95 Autori con 124 Opere. Sono state effettuate 190 letture. A conclusione delle due giornate, la Commissione Selezionatrice, composta dai Signori Susanna Bertoni, Federica Cerami, Renza Grossi, Saverio Langianni, Enzo Gabriele Leanza, Monica Mazzolini e Fulvio Merlak (Presidente di Giuria) (Francesca Lampredi ha svolto unicamente funzioni di Lettrice), ha assegnato i riconoscimenti come segue:<br \/>\n&nbsp;<br \/>\n<strong>1\u00b0 Premio<\/strong> a <strong>\u00ab<\/strong><strong>Immanenza\u00bb<\/strong> di <strong>Barbara FIORILLO<\/strong> di Napoli<br \/>\n(Portfolio composto da 25 immagini a Colori realizzate nel 2020)<br \/>\ncon la seguente motivazione:<br \/>\n\u00abIl racconto, costruito all&#8217;interno di una cornice di luce, si snoda lungo piccole riflessioni di un difficile quotidiano appena trascorso e lascia trasparire, tassello dopo tassello, un mosaico di emozioni da poter comporre lungo la linea di un tempo immobile e sospeso. Le immagini, dal carattere fortemente metafisico, accompagnano lo spettatore in una dimensione protetta e intima, nella quale il candore del bianco sembra dichiararsi come apertura verso una prossima e necessaria catarsi. Lo spunto narrativo della chiusura del mondo a causa dell\u2019avanzata del Coronavirus, struttura il racconto in una lunga sequenza di \u201ctracce di Pollicino\u201d, da poter leggere, volendo, come espressione del proprio mondo emotivo.\u00bb<br \/>\n&nbsp;<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-1727 aligncenter\" src=\"https:\/\/fiaf.net\/portfolioitalia\/wp-content\/uploads\/2020\/06\/Barbara-Fiorillo-Immanenza-15-quarantena-1024x681.jpg\" alt=\"Barbara Fiorillo - Immanenza - 15 (quarantena)\" width=\"1024\" height=\"681\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-1726 aligncenter\" src=\"https:\/\/fiaf.net\/portfolioitalia\/wp-content\/uploads\/sites\/27\/2020\/06\/Immanenza-01-Barbara-Fiorillo-724x1024.jpg\" alt=\"Immanenza 01 - Barbara Fiorillo\" width=\"724\" height=\"1024\" srcset=\"https:\/\/fiaf.net\/portfolioitalia\/wp-content\/uploads\/sites\/27\/2020\/06\/Immanenza-01-Barbara-Fiorillo-724x1024.jpg 724w, https:\/\/fiaf.net\/portfolioitalia\/wp-content\/uploads\/sites\/27\/2020\/06\/Immanenza-01-Barbara-Fiorillo-212x300.jpg 212w, https:\/\/fiaf.net\/portfolioitalia\/wp-content\/uploads\/sites\/27\/2020\/06\/Immanenza-01-Barbara-Fiorillo-768x1086.jpg 768w, https:\/\/fiaf.net\/portfolioitalia\/wp-content\/uploads\/sites\/27\/2020\/06\/Immanenza-01-Barbara-Fiorillo-1086x1536.jpg 1086w, https:\/\/fiaf.net\/portfolioitalia\/wp-content\/uploads\/sites\/27\/2020\/06\/Immanenza-01-Barbara-Fiorillo.jpg 1241w\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-1725 aligncenter\" src=\"https:\/\/fiaf.net\/portfolioitalia\/wp-content\/uploads\/sites\/27\/2020\/06\/Immanenza-02-Barbara-Fiorillo-925x1024.jpg\" alt=\"Immanenza 02 - Barbara Fiorillo\" width=\"925\" height=\"1024\" srcset=\"https:\/\/fiaf.net\/portfolioitalia\/wp-content\/uploads\/sites\/27\/2020\/06\/Immanenza-02-Barbara-Fiorillo-925x1024.jpg 925w, https:\/\/fiaf.net\/portfolioitalia\/wp-content\/uploads\/sites\/27\/2020\/06\/Immanenza-02-Barbara-Fiorillo-271x300.jpg 271w, https:\/\/fiaf.net\/portfolioitalia\/wp-content\/uploads\/sites\/27\/2020\/06\/Immanenza-02-Barbara-Fiorillo-768x851.jpg 768w, https:\/\/fiaf.net\/portfolioitalia\/wp-content\/uploads\/sites\/27\/2020\/06\/Immanenza-02-Barbara-Fiorillo.jpg 1238w\" sizes=\"auto, (max-width: 925px) 100vw, 925px\" \/><strong>2\u00b0 Premio<\/strong> a <strong>\u00ab<\/strong><strong>#Daily Triptych\u00bb<\/strong> di <strong>Sara ROSSATELLI<\/strong> di Dresano (Milano)<br \/>\n(Portfolio composto da 24 trittici a Colori realizzati nel 2020)<br \/>\ncon la seguente motivazione:<br \/>\n\u00abPer la capacit\u00e0 di raccontare l\u2019esperienza quotidiana di un piccolo mondo sospeso tra realt\u00e0 e immaginazione con delicata raffinatezza. Per aver saputo rileggere la drammaticit\u00e0 degli eventi che ci hanno travolto attraverso una creativit\u00e0 fresca e dirompente. E infine, per averci regalato ventiquattro volte l\u2019immagine di una vita divisa in tre.\u00bb<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-1724 aligncenter\" src=\"https:\/\/fiaf.net\/portfolioitalia\/wp-content\/uploads\/sites\/27\/2020\/06\/Sara-Rossatelli-DailyTriptych-14-361x1024.jpg\" alt=\"Sara Rossatelli - #DailyTriptych - 14\" width=\"361\" height=\"1024\" srcset=\"https:\/\/fiaf.net\/portfolioitalia\/wp-content\/uploads\/sites\/27\/2020\/06\/Sara-Rossatelli-DailyTriptych-14-361x1024.jpg 361w, https:\/\/fiaf.net\/portfolioitalia\/wp-content\/uploads\/sites\/27\/2020\/06\/Sara-Rossatelli-DailyTriptych-14-106x300.jpg 106w, https:\/\/fiaf.net\/portfolioitalia\/wp-content\/uploads\/sites\/27\/2020\/06\/Sara-Rossatelli-DailyTriptych-14-541x1536.jpg 541w, https:\/\/fiaf.net\/portfolioitalia\/wp-content\/uploads\/sites\/27\/2020\/06\/Sara-Rossatelli-DailyTriptych-14.jpg 705w\" sizes=\"auto, (max-width: 361px) 100vw, 361px\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-1723 aligncenter\" src=\"https:\/\/fiaf.net\/portfolioitalia\/wp-content\/uploads\/sites\/27\/2020\/06\/Daily-Triptych-01-Sara-Rossatelli-724x1024.jpg\" alt=\"#Daily Triptych 01 - Sara Rossatelli\" width=\"724\" height=\"1024\" srcset=\"https:\/\/fiaf.net\/portfolioitalia\/wp-content\/uploads\/sites\/27\/2020\/06\/Daily-Triptych-01-Sara-Rossatelli-724x1024.jpg 724w, https:\/\/fiaf.net\/portfolioitalia\/wp-content\/uploads\/sites\/27\/2020\/06\/Daily-Triptych-01-Sara-Rossatelli-212x300.jpg 212w, https:\/\/fiaf.net\/portfolioitalia\/wp-content\/uploads\/sites\/27\/2020\/06\/Daily-Triptych-01-Sara-Rossatelli-768x1086.jpg 768w, https:\/\/fiaf.net\/portfolioitalia\/wp-content\/uploads\/sites\/27\/2020\/06\/Daily-Triptych-01-Sara-Rossatelli-1086x1536.jpg 1086w, https:\/\/fiaf.net\/portfolioitalia\/wp-content\/uploads\/sites\/27\/2020\/06\/Daily-Triptych-01-Sara-Rossatelli.jpg 1241w\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-1722 aligncenter\" src=\"https:\/\/fiaf.net\/portfolioitalia\/wp-content\/uploads\/sites\/27\/2020\/06\/Daily-Triptych-02-Sara-Rossatelli-1024x557.jpg\" alt=\"#Daily Triptych 02 - Sara Rossatelli\" width=\"1024\" height=\"557\" srcset=\"https:\/\/fiaf.net\/portfolioitalia\/wp-content\/uploads\/sites\/27\/2020\/06\/Daily-Triptych-02-Sara-Rossatelli-1024x557.jpg 1024w, https:\/\/fiaf.net\/portfolioitalia\/wp-content\/uploads\/sites\/27\/2020\/06\/Daily-Triptych-02-Sara-Rossatelli-300x163.jpg 300w, https:\/\/fiaf.net\/portfolioitalia\/wp-content\/uploads\/sites\/27\/2020\/06\/Daily-Triptych-02-Sara-Rossatelli-768x418.jpg 768w, https:\/\/fiaf.net\/portfolioitalia\/wp-content\/uploads\/sites\/27\/2020\/06\/Daily-Triptych-02-Sara-Rossatelli.jpg 1240w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n\n    <div class=\"xs_social_share_widget xs_share_url after_content \t\tmain_content  wslu-style-1 wslu-share-box-shaped wslu-fill-colored wslu-none wslu-share-horizontal wslu-theme-font-no wslu-main_content\">\n\n\t\t\n        <ul>\n\t\t\t        <\/ul>\n    <\/div> \n","protected":false},"excerpt":{"rendered":"<p>Risultati del\u00a0\u00ab17\u00b0 FotoArte in Portfolio\u00bb\u00a0seconda delle dieci Selezioni aderenti a\u00a0\u00abPortfolio Italia 2020\u00a0\u2013 Gran Premio Fujifilm\u00bb Il \u00ab17\u00b0 FotoArte in Portfolio\u00bb &hellip;<\/p>\n","protected":false},"author":63,"featured_media":1727,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1718","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-risultati-tappe-2020"],"acf":[],"_links":{"self":[{"href":"https:\/\/fiaf.net\/portfolioitalia\/wp-json\/wp\/v2\/posts\/1718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fiaf.net\/portfolioitalia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fiaf.net\/portfolioitalia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fiaf.net\/portfolioitalia\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/fiaf.net\/portfolioitalia\/wp-json\/wp\/v2\/comments?post=1718"}],"version-history":[{"count":0,"href":"https:\/\/fiaf.net\/portfolioitalia\/wp-json\/wp\/v2\/posts\/1718\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fiaf.net\/portfolioitalia\/wp-json\/wp\/v2\/media\/1727"}],"wp:attachment":[{"href":"https:\/\/fiaf.net\/portfolioitalia\/wp-json\/wp\/v2\/media?parent=1718"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fiaf.net\/portfolioitalia\/wp-json\/wp\/v2\/categories?post=1718"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fiaf.net\/portfolioitalia\/wp-json\/wp\/v2\/tags?post=1718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}