{"id":3702,"date":"2014-01-12T21:24:36","date_gmt":"2014-01-12T20:24:36","guid":{"rendered":"https:\/\/fiaf.net\/regioni\/veneto\/?p=3702"},"modified":"2014-01-12T21:24:36","modified_gmt":"2014-01-12T20:24:36","slug":"wahrheit-macht-frei","status":"publish","type":"post","link":"https:\/\/fiaf.net\/veneto\/wahrheit-macht-frei\/","title":{"rendered":"Wahrheit macht frei"},"content":{"rendered":"<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-3703\" alt=\"Template Piccolo formato\" src=\"https:\/\/fiaf.net\/regioni\/veneto\/wp-content\/uploads\/2014\/01\/locandina-light-725x1024.jpg\" width=\"507\" height=\"717\" \/><\/p>\n<p>Gentile FIAF, il <strong>fotoclub RUZANTE<\/strong> di Pernumia \u00e8 lieto di presentare la MOSTRA FOTOGRAFICA Wahrheit macht frei &#8211; Auschwitz &#8211; La verit\u00e0 rende liberi di Elisa Mortin e Giancarlo Soncin, nostri soci.<br \/>\nQuest&#8217;anno siamo ospiti del Comune di Padova, presso le <strong>scuderie di Palazzo Moroni<\/strong> ed apriamo l&#8217;invito di partecipazione a tutti i fotoclub ed appassionati di fotografia. L&#8217;ingresso \u00e8 libero.<br \/>\nL&#8217;inaugurazione con le Autorit\u00e0 sar\u00e0 giovedi 23 gennaio alle ore 18.00 ed \u00e8 previsto in incontro di approfondimento con gli Autori sabato 25 gennaio alle ore 17.00.<br \/>\nLa mostra si compone di circa 100 scatti in bianco e nero raccolti durante 3 viaggi in Polonia tra il 2012 e il 2013 ed \u00e8 corredata da contenuti storici che conducono il visitatore in un viaggio a ritroso nel tempo, calandolo nella drammatica realt\u00e0 di un Campo di Concentramento.<br \/>\nQuest&#8217;anno i nostri soci presenteranno una audioguida interattiva gratuita a corredo della mostra (utilizzabile attraverso uno smartphone con connessione ad internet, un lettore QRcode installato nel telefono, e delle cuffiette) e tutti i testi esposti nei pannelli saranno sia in Italiano che in Inglese. Sar\u00e0 anche presentato un libro fotografico con gli scatti presentati alla manifestazione.<br \/>\nL&#8217;evento \u00e8 patrocinato dal Giardino dei Giusti del Mondo (sez. padovana), dalla Comunit\u00e0 ebraica di Padova, dal MIUR Veneto, dall&#8217;Universit\u00e0 degli studi di Padova, dall&#8217;ISVREC (Istituto veneto per la storia della Resistenza e dell&#8217;et\u00e0 contemporanea), dal Web Memo ( European Digitalization of Shared Memories), dalla FIAF con riconoscimento n\u00b0F04\/14.<br \/>\nPer rimanere aggiornati sull&#8217;evento potete iscrivervi alla pagina facebook: https:\/\/www.facebook.com\/events\/593043034083706\/?fref=ts<br \/>\nIntroduzione alla mostra:<br \/>\n&lt;&lt;Visitatore, osserva le vestigia di questo campo e medita: da qualunque paese tu venga, tu non sei un estraneo. Fa che il tuo viaggio non sia stato inutile, che non sia stata inutile la nostra morte. Per te e per i tuoi figli, le ceneri di Auschwitz valgano di ammonimento: fa che il frutto orrendo dell\u2019odio, di cui hai visto qui le tracce, non dia nuovo seme, n\u00e9 domani n\u00e9 mai&gt;&gt;.<br \/>\n(Primo Levi \u2013 Memoriale italiano ad Auschwitz).<br \/>\nRipercorrendo la tematica della Shoa con lo stesso spirito auspicato dalle parole di Levi, presentiamo una mostra fotografica sul campo di concentramento e sterminio di Auschwitz, per non sottrarre alla memoria il capitolo pi\u00f9 buio della storia moderna, quello che \u00e8 stato definito &#8220;il male assoluto, impunibile e imperdonabile&#8221;. Un reportage in bianco e nero da cui traspare la quotidianit\u00e0 dei deportati e si evocano immani tragedie: la vita nel campo, le privazioni continue, le incessanti brutalit\u00e0, le esecuzioni sommarie.<br \/>\nLe immagini catturano ci\u00f2 che resta, oggetti in primis. E\u2019 materia che sopravvive ai corpi, alla quale si d\u00e0 ruolo di testimonianza: valigie, occhiali, scarpe, capelli.<br \/>\nUn invito a interrogarci su come questo sia potuto accadere nell\u2019Europa civile e progredita della met\u00e0 del Novecento.<br \/>\nCordiali saluti a tutti<br \/>\nIl fotoclub Ruzante di Pernumia<br \/>\nFOTOCLUB RUZANTE DI PERNUMIA<br \/>\nvia A. Beolco<br \/>\n35020 Pernumia (PD)<br \/>\nwww.fotoclubruzante.it<br \/>\nFacebook: https:\/\/www.facebook.com\/fotoclub.ruzante<br \/>\nIncontri: ogni giovedi ore 21.00 presso Centro Socioculturale<br \/>\nPresidente: ROBERTO BARNES<br \/>\n347.8208193<br \/>\n&nbsp;<\/p>\n\n    <div class=\"xs_social_share_widget xs_share_url after_content \t\tmain_content  wslu-style-1 wslu-share-box-shaped wslu-fill-colored wslu-none wslu-share-horizontal wslu-theme-font-no wslu-main_content\">\n\n\t\t\n        <ul>\n\t\t\t        <\/ul>\n    <\/div> \n","protected":false},"excerpt":{"rendered":"<p>Gentile FIAF, il fotoclub RUZANTE di Pernumia \u00e8 lieto di presentare la MOSTRA FOTOGRAFICA Wahrheit macht frei &#8211; Auschwitz &#8211; &hellip;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-3702","post","type-post","status-publish","format-standard","hentry","category-mostre"],"acf":[],"_links":{"self":[{"href":"https:\/\/fiaf.net\/veneto\/wp-json\/wp\/v2\/posts\/3702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fiaf.net\/veneto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fiaf.net\/veneto\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fiaf.net\/veneto\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/fiaf.net\/veneto\/wp-json\/wp\/v2\/comments?post=3702"}],"version-history":[{"count":0,"href":"https:\/\/fiaf.net\/veneto\/wp-json\/wp\/v2\/posts\/3702\/revisions"}],"wp:attachment":[{"href":"https:\/\/fiaf.net\/veneto\/wp-json\/wp\/v2\/media?parent=3702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fiaf.net\/veneto\/wp-json\/wp\/v2\/categories?post=3702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fiaf.net\/veneto\/wp-json\/wp\/v2\/tags?post=3702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}